{"id":6191,"date":"2024-05-29T07:00:14","date_gmt":"2024-05-29T07:00:14","guid":{"rendered":"https:\/\/tehni.eu.www425.your-server.de\/?page_id=6191"},"modified":"2025-06-10T13:56:43","modified_gmt":"2025-06-10T10:56:43","slug":"products-showcase","status":"publish","type":"page","link":"https:\/\/tehni.eu\/it\/products-showcase\/","title":{"rendered":"Prodotti"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6191\" class=\"elementor elementor-6191\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"page\">\n\t\t\t\t<section class=\"elementor-element elementor-element-78ba7a1 e-flex e-con-boxed e-con e-parent\" data-id=\"78ba7a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17797be heading-h2 heading-h2-left elementor-widget elementor-widget-heading\" data-id=\"17797be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Prodotti<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57bf4f7 e-con-full e-grid e-con e-child\" data-id=\"57bf4f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bf63d4f e-con-full clickable-parent pds-ed e-flex e-con e-child\" data-id=\"bf63d4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cea527 elementor-widget elementor-widget-image\" data-id=\"2cea527\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tehni.eu\/it\/secure-and-stylish-entrance-doors\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"875\" src=\"https:\/\/tehni.eu\/wp-content\/uploads\/Entrance_Doors0.webp\" class=\"attachment-full size-full wp-image-9840\" alt=\"\" srcset=\"https:\/\/tehni.eu\/wp-content\/uploads\/Entrance_Doors0.webp 1000w, https:\/\/tehni.eu\/wp-content\/uploads\/Entrance_Doors0-600x525.webp 600w, https:\/\/tehni.eu\/wp-content\/uploads\/Entrance_Doors0-768x672.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8316bb3 elementor-widget elementor-widget-heading\" data-id=\"8316bb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tehni.eu\/it\/secure-and-stylish-entrance-doors\/\">Porte d'ingresso<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad1c30a e-con-full clickable-parent pds-dp e-flex e-con e-child\" data-id=\"ad1c30a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f42b4 elementor-widget elementor-widget-image\" data-id=\"c6f42b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tehni.eu\/it\/door-panels\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"875\" src=\"https:\/\/tehni.eu\/wp-content\/uploads\/Panels0.webp\" class=\"attachment-full size-full wp-image-9841\" alt=\"\" srcset=\"https:\/\/tehni.eu\/wp-content\/uploads\/Panels0.webp 1000w, https:\/\/tehni.eu\/wp-content\/uploads\/Panels0-600x525.webp 600w, https:\/\/tehni.eu\/wp-content\/uploads\/Panels0-768x672.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7267b43 elementor-widget elementor-widget-heading\" data-id=\"7267b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tehni.eu\/it\/door-panels\/\">Pannelli porta<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b152f81 e-con-full clickable-parent pds-is e-flex e-con e-child\" data-id=\"b152f81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5a5557 elementor-widget elementor-widget-image\" data-id=\"c5a5557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tehni.eu\/it\/insect-screens\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"875\" src=\"https:\/\/tehni.eu\/wp-content\/uploads\/Insect_Screen_100.webp\" class=\"attachment-full size-full wp-image-9843\" alt=\"\" srcset=\"https:\/\/tehni.eu\/wp-content\/uploads\/Insect_Screen_100.webp 1000w, https:\/\/tehni.eu\/wp-content\/uploads\/Insect_Screen_100-600x525.webp 600w, https:\/\/tehni.eu\/wp-content\/uploads\/Insect_Screen_100-768x672.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-718f340 elementor-widget elementor-widget-heading\" data-id=\"718f340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tehni.eu\/it\/insect-screens\/\">Schermi per insetti<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-035cded e-con-full clickable-parent pds-af e-flex e-con e-child\" data-id=\"035cded\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57ee549 elementor-widget elementor-widget-image\" data-id=\"57ee549\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tehni.eu\/it\/aluminium-facings\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"875\" src=\"https:\/\/tehni.eu\/wp-content\/uploads\/Aluminium_Facing0.webp\" class=\"attachment-full size-full wp-image-9842\" alt=\"\" srcset=\"https:\/\/tehni.eu\/wp-content\/uploads\/Aluminium_Facing0.webp 1000w, https:\/\/tehni.eu\/wp-content\/uploads\/Aluminium_Facing0-600x525.webp 600w, https:\/\/tehni.eu\/wp-content\/uploads\/Aluminium_Facing0-768x672.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7a43f elementor-widget elementor-widget-heading\" data-id=\"5d7a43f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tehni.eu\/it\/aluminium-facings\/\">Rivestimenti in alluminio<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-912869d e-con-full clickable-parent pds-af e-flex e-con e-child\" data-id=\"912869d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30d2b4b elementor-widget elementor-widget-image\" data-id=\"30d2b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tehni.eu\/it\/gripline-handles\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"875\" src=\"https:\/\/tehni.eu\/wp-content\/uploads\/gripline-products-featured.webp\" class=\"attachment-full size-full wp-image-14496\" alt=\"\" srcset=\"https:\/\/tehni.eu\/wp-content\/uploads\/gripline-products-featured.webp 1000w, https:\/\/tehni.eu\/wp-content\/uploads\/gripline-products-featured-600x525.webp 600w, https:\/\/tehni.eu\/wp-content\/uploads\/gripline-products-featured-768x672.webp 768w, https:\/\/tehni.eu\/wp-content\/uploads\/gripline-products-featured-14x12.webp 14w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9eb3e3 elementor-widget elementor-widget-heading\" data-id=\"b9eb3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GripLine Handles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Products Entrance Doors Door Panels Insect Screens Aluminium Facings GripLine Handles<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"hf_cat_page":[183],"class_list":["post-6191","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/pages\/6191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/comments?post=6191"}],"version-history":[{"count":0,"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/pages\/6191\/revisions"}],"wp:attachment":[{"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/media?parent=6191"}],"wp:term":[{"taxonomy":"hf_cat_page","embeddable":true,"href":"https:\/\/tehni.eu\/it\/wp-json\/wp\/v2\/hf_cat_page?post=6191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}